{"id":17149,"date":"2025-05-06T07:29:29","date_gmt":"2025-05-06T07:29:29","guid":{"rendered":"https:\/\/www.vtmarkets.net\/fr\/?p=17149"},"modified":"2025-05-06T07:31:15","modified_gmt":"2025-05-06T07:31:15","slug":"v2025050601","status":"publish","type":"post","link":"https:\/\/www.vtmarkets.net\/fr\/dividend\/v2025050601\/","title":{"rendered":"Avis d&#8217;ajustement des dividendes &#8211; May 06 ,2025"},"content":{"rendered":"\n<p>\n    Cher Client,\n<\/p>\n<p>\n    Veuillez noter que les dividendes des produits suivants seront ajust\u00e9s en cons\u00e9quence. Les dividendes des indices seront ex\u00e9cut\u00e9s s\u00e9par\u00e9ment via un relev\u00e9 de solde directement sur votre compte de trading, et le commentaire sera au format suivant : \u201cDiv &#038; Nom du produit &#038; Volume net\u201d.\n<\/p>\n<p>\n    Veuillez consulter le tableau ci-dessous pour plus de d\u00e9tails :\n<\/p>\n<p>\n<img decoding=\"async\" src=\"\/email_img\/email_fr2025050601.jpg\" alt=\"Avis d'ajustement des dividendes\" width=\"660\" height=\"483\">\n<\/p>\n<p>\n    Les donn\u00e9es ci-dessus sont fournies \u00e0 titre de r\u00e9f\u00e9rence uniquement, veuillez consulter le logiciel MT4\/MT5 pour des informations pr\u00e9cises.\n<\/p>\n<p>\n    Pour toute information compl\u00e9mentaire, n&#8217;h\u00e9sitez pas \u00e0 contacter  <a href=\"mailto:info@vtmarkets.com\">info@vtmarkets.com.<\/a>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cher Client, Veuillez noter que les dividendes des produits suivants seront ajust\u00e9s en cons\u00e9quence. Les dividendes des indices seront ex\u00e9cut\u00e9s s\u00e9par\u00e9ment via un relev\u00e9 de solde directement sur votre compte de trading, et le commentaire sera au format suivant : \u201cDiv &#038; Nom du produit &#038; Volume net\u201d. Veuillez consulter le tableau ci-dessous pour plus <a href=\"https:\/\/www.vtmarkets.net\/fr\/dividend\/v2025050601\/\" class=\"read-more\">Continue Reading<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-17149","post","type-post","status-publish","format-standard","hentry","category-dividend"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.5.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"Cher Client, Veuillez noter que les dividendes des produits suivants seront ajust\u00e9s en cons\u00e9quence. Les dividendes des indices seront ex\u00e9cut\u00e9s s\u00e9par\u00e9ment via un relev\u00e9 de solde directement sur votre compte de trading, et le commentaire sera au format suivant : \u201cDiv &amp; Nom du produit &amp; Volume net\u201d. Veuillez consulter le tableau ci-dessous pour plus\" \/>\n\t<meta name=\"robots\" content=\"noindex, noimageindex, max-snippet:-1, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"lucky\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.vtmarkets.net\/fr\/dividend\/v2025050601\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.5.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"VT Markets -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Avis d\u2019ajustement des dividendes \u2013 May 06 ,2025 - VT Markets\" \/>\n\t\t<meta property=\"og:description\" content=\"Cher Client, Veuillez noter que les dividendes des produits suivants seront ajust\u00e9s en cons\u00e9quence. Les dividendes des indices seront ex\u00e9cut\u00e9s s\u00e9par\u00e9ment via un relev\u00e9 de solde directement sur votre compte de trading, et le commentaire sera au format suivant : \u201cDiv &amp; Nom du produit &amp; Volume net\u201d. Veuillez consulter le tableau ci-dessous pour plus\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.vtmarkets.net\/fr\/dividend\/v2025050601\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-05-06T07:29:29+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-05-06T07:31:15+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Avis d\u2019ajustement des dividendes \u2013 May 06 ,2025 - VT Markets\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Cher Client, Veuillez noter que les dividendes des produits suivants seront ajust\u00e9s en cons\u00e9quence. Les dividendes des indices seront ex\u00e9cut\u00e9s s\u00e9par\u00e9ment via un relev\u00e9 de solde directement sur votre compte de trading, et le commentaire sera au format suivant : \u201cDiv &amp; Nom du produit &amp; Volume net\u201d. Veuillez consulter le tableau ci-dessous pour plus\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/dividend\\\/v2025050601\\\/#blogposting\",\"name\":\"Avis d\\u2019ajustement des dividendes \\u2013 May 06 ,2025 - VT Markets\",\"headline\":\"Avis d&#8217;ajustement des dividendes &#8211; May 06 ,2025\",\"author\":{\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/author\\\/lucky\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"\\\/email_img\\\/email_fr2025050601.jpg\",\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/dividend\\\/v2025050601\\\/#articleImage\"},\"datePublished\":\"2025-05-06T07:29:29+00:00\",\"dateModified\":\"2025-05-06T07:31:15+00:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/dividend\\\/v2025050601\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/dividend\\\/v2025050601\\\/#webpage\"},\"articleSection\":\"Dividend\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/dividend\\\/v2025050601\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/category\\\/dividend\\\/#listItem\",\"name\":\"Dividend\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/category\\\/dividend\\\/#listItem\",\"position\":2,\"name\":\"Dividend\",\"item\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/category\\\/dividend\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/dividend\\\/v2025050601\\\/#listItem\",\"name\":\"Avis d&#8217;ajustement des dividendes &#8211; May 06 ,2025\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/dividend\\\/v2025050601\\\/#listItem\",\"position\":3,\"name\":\"Avis d&#8217;ajustement des dividendes &#8211; May 06 ,2025\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/category\\\/dividend\\\/#listItem\",\"name\":\"Dividend\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/#organization\",\"name\":\"VT Markets\",\"url\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/author\\\/lucky\\\/#author\",\"url\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/author\\\/lucky\\\/\",\"name\":\"lucky\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/dividend\\\/v2025050601\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de1bc14bcef0fdecf286e29d3fd3ccc880a0fae5b00f57b5aff4237fcad8e365?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"lucky\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/dividend\\\/v2025050601\\\/#webpage\",\"url\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/dividend\\\/v2025050601\\\/\",\"name\":\"Avis d\\u2019ajustement des dividendes \\u2013 May 06 ,2025 - VT Markets\",\"description\":\"Cher Client, Veuillez noter que les dividendes des produits suivants seront ajust\\u00e9s en cons\\u00e9quence. Les dividendes des indices seront ex\\u00e9cut\\u00e9s s\\u00e9par\\u00e9ment via un relev\\u00e9 de solde directement sur votre compte de trading, et le commentaire sera au format suivant : \\u201cDiv & Nom du produit & Volume net\\u201d. Veuillez consulter le tableau ci-dessous pour plus\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/dividend\\\/v2025050601\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/author\\\/lucky\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/author\\\/lucky\\\/#author\"},\"datePublished\":\"2025-05-06T07:29:29+00:00\",\"dateModified\":\"2025-05-06T07:31:15+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/\",\"name\":\"VT Markets\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vtmarkets.net\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Avis d\u2019ajustement des dividendes \u2013 May 06 ,2025 - VT Markets<\/title>\n\n","aioseo_head_json":{"title":"Avis d\u2019ajustement des dividendes \u2013 May 06 ,2025 - VT Markets","description":"Cher Client, Veuillez noter que les dividendes des produits suivants seront ajust\u00e9s en cons\u00e9quence. Les dividendes des indices seront ex\u00e9cut\u00e9s s\u00e9par\u00e9ment via un relev\u00e9 de solde directement sur votre compte de trading, et le commentaire sera au format suivant : \u201cDiv & Nom du produit & Volume net\u201d. Veuillez consulter le tableau ci-dessous pour plus","canonical_url":"https:\/\/www.vtmarkets.net\/fr\/dividend\/v2025050601\/","robots":"noindex, noimageindex, max-snippet:-1, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.vtmarkets.net\/fr\/dividend\/v2025050601\/#blogposting","name":"Avis d\u2019ajustement des dividendes \u2013 May 06 ,2025 - VT Markets","headline":"Avis d&#8217;ajustement des dividendes &#8211; May 06 ,2025","author":{"@id":"https:\/\/www.vtmarkets.net\/fr\/author\/lucky\/#author"},"publisher":{"@id":"https:\/\/www.vtmarkets.net\/fr\/#organization"},"image":{"@type":"ImageObject","url":"\/email_img\/email_fr2025050601.jpg","@id":"https:\/\/www.vtmarkets.net\/fr\/dividend\/v2025050601\/#articleImage"},"datePublished":"2025-05-06T07:29:29+00:00","dateModified":"2025-05-06T07:31:15+00:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.vtmarkets.net\/fr\/dividend\/v2025050601\/#webpage"},"isPartOf":{"@id":"https:\/\/www.vtmarkets.net\/fr\/dividend\/v2025050601\/#webpage"},"articleSection":"Dividend"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vtmarkets.net\/fr\/dividend\/v2025050601\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.vtmarkets.net\/fr#listItem","position":1,"name":"Home","item":"https:\/\/www.vtmarkets.net\/fr","nextItem":{"@type":"ListItem","@id":"https:\/\/www.vtmarkets.net\/fr\/category\/dividend\/#listItem","name":"Dividend"}},{"@type":"ListItem","@id":"https:\/\/www.vtmarkets.net\/fr\/category\/dividend\/#listItem","position":2,"name":"Dividend","item":"https:\/\/www.vtmarkets.net\/fr\/category\/dividend\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.vtmarkets.net\/fr\/dividend\/v2025050601\/#listItem","name":"Avis d&#8217;ajustement des dividendes &#8211; May 06 ,2025"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.vtmarkets.net\/fr#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.vtmarkets.net\/fr\/dividend\/v2025050601\/#listItem","position":3,"name":"Avis d&#8217;ajustement des dividendes &#8211; May 06 ,2025","previousItem":{"@type":"ListItem","@id":"https:\/\/www.vtmarkets.net\/fr\/category\/dividend\/#listItem","name":"Dividend"}}]},{"@type":"Organization","@id":"https:\/\/www.vtmarkets.net\/fr\/#organization","name":"VT Markets","url":"https:\/\/www.vtmarkets.net\/fr\/"},{"@type":"Person","@id":"https:\/\/www.vtmarkets.net\/fr\/author\/lucky\/#author","url":"https:\/\/www.vtmarkets.net\/fr\/author\/lucky\/","name":"lucky","image":{"@type":"ImageObject","@id":"https:\/\/www.vtmarkets.net\/fr\/dividend\/v2025050601\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/de1bc14bcef0fdecf286e29d3fd3ccc880a0fae5b00f57b5aff4237fcad8e365?s=96&d=mm&r=g","width":96,"height":96,"caption":"lucky"}},{"@type":"WebPage","@id":"https:\/\/www.vtmarkets.net\/fr\/dividend\/v2025050601\/#webpage","url":"https:\/\/www.vtmarkets.net\/fr\/dividend\/v2025050601\/","name":"Avis d\u2019ajustement des dividendes \u2013 May 06 ,2025 - VT Markets","description":"Cher Client, Veuillez noter que les dividendes des produits suivants seront ajust\u00e9s en cons\u00e9quence. Les dividendes des indices seront ex\u00e9cut\u00e9s s\u00e9par\u00e9ment via un relev\u00e9 de solde directement sur votre compte de trading, et le commentaire sera au format suivant : \u201cDiv & Nom du produit & Volume net\u201d. Veuillez consulter le tableau ci-dessous pour plus","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.vtmarkets.net\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/www.vtmarkets.net\/fr\/dividend\/v2025050601\/#breadcrumblist"},"author":{"@id":"https:\/\/www.vtmarkets.net\/fr\/author\/lucky\/#author"},"creator":{"@id":"https:\/\/www.vtmarkets.net\/fr\/author\/lucky\/#author"},"datePublished":"2025-05-06T07:29:29+00:00","dateModified":"2025-05-06T07:31:15+00:00"},{"@type":"WebSite","@id":"https:\/\/www.vtmarkets.net\/fr\/#website","url":"https:\/\/www.vtmarkets.net\/fr\/","name":"VT Markets","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.vtmarkets.net\/fr\/#organization"}}]},"og:locale":"en_US","og:site_name":"VT Markets -","og:type":"article","og:title":"Avis d\u2019ajustement des dividendes \u2013 May 06 ,2025 - VT Markets","og:description":"Cher Client, Veuillez noter que les dividendes des produits suivants seront ajust\u00e9s en cons\u00e9quence. Les dividendes des indices seront ex\u00e9cut\u00e9s s\u00e9par\u00e9ment via un relev\u00e9 de solde directement sur votre compte de trading, et le commentaire sera au format suivant : \u201cDiv &amp; Nom du produit &amp; Volume net\u201d. Veuillez consulter le tableau ci-dessous pour plus","og:url":"https:\/\/www.vtmarkets.net\/fr\/dividend\/v2025050601\/","article:published_time":"2025-05-06T07:29:29+00:00","article:modified_time":"2025-05-06T07:31:15+00:00","twitter:card":"summary_large_image","twitter:title":"Avis d\u2019ajustement des dividendes \u2013 May 06 ,2025 - VT Markets","twitter:description":"Cher Client, Veuillez noter que les dividendes des produits suivants seront ajust\u00e9s en cons\u00e9quence. Les dividendes des indices seront ex\u00e9cut\u00e9s s\u00e9par\u00e9ment via un relev\u00e9 de solde directement sur votre compte de trading, et le commentaire sera au format suivant : \u201cDiv &amp; Nom du produit &amp; Volume net\u201d. Veuillez consulter le tableau ci-dessous pour plus"},"aioseo_meta_data":{"post_id":"17149","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":false,"robots_noindex":true,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":true,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-08-15 04:55:47","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2025-05-06 07:29:31","updated":"2025-08-15 04:55:47"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.vtmarkets.net\/fr\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.vtmarkets.net\/fr\/category\/dividend\/\" title=\"Dividend\">Dividend<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tAvis d\u2019ajustement des dividendes \u2013 May 06 ,2025\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.vtmarkets.net\/fr"},{"label":"Dividend","link":"https:\/\/www.vtmarkets.net\/fr\/category\/dividend\/"},{"label":"Avis d&#8217;ajustement des dividendes &#8211; May 06 ,2025","link":"https:\/\/www.vtmarkets.net\/fr\/dividend\/v2025050601\/"}],"_links":{"self":[{"href":"https:\/\/www.vtmarkets.net\/fr\/wp-json\/wp\/v2\/posts\/17149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vtmarkets.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vtmarkets.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vtmarkets.net\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vtmarkets.net\/fr\/wp-json\/wp\/v2\/comments?post=17149"}],"version-history":[{"count":0,"href":"https:\/\/www.vtmarkets.net\/fr\/wp-json\/wp\/v2\/posts\/17149\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.vtmarkets.net\/fr\/wp-json\/wp\/v2\/media?parent=17149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vtmarkets.net\/fr\/wp-json\/wp\/v2\/categories?post=17149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vtmarkets.net\/fr\/wp-json\/wp\/v2\/tags?post=17149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}