{"id":17211,"date":"2025-08-19T07:33:03","date_gmt":"2025-08-19T07:33:03","guid":{"rendered":"https:\/\/www.vtmarkets.net\/de\/?p=17211"},"modified":"2025-08-19T07:37:05","modified_gmt":"2025-08-19T07:37:05","slug":"v2025081901","status":"publish","type":"post","link":"https:\/\/www.vtmarkets.net\/de\/dividend\/v2025081901\/","title":{"rendered":"Mitteilung zur Dividendenanpassung &#8211; Aug 19 ,2025"},"content":{"rendered":"\n<p>\n    Sehr geehrter Kunde,\n<\/p>\n<p>\n    Bitte beachten Sie, dass die Dividenden der folgenden Produkte entsprechend angepasst werden. Index-Dividenden werden separat \u00fcber eine Kontoabrechnung direkt auf Ihr Handelskonto gebucht. Der Kommentar dazu erfolgt im folgenden Format: \u201eDiv &#038; Produktname &#038; Nettovolumen\u201c.\n<\/p>\n<p>\n    Bitte beachten Sie die folgende Tabelle f\u00fcr weitere Details:\n<\/p>\n<p>\n<img decoding=\"async\" src=\"\/email_img\/email_de2025081901.jpg\" alt=\"Mitteilung zur Dividendenanpassung\" width=\"660\" height=\"587\">\n<\/p>\n<p>\n    Die obigen Daten dienen nur zur Orientierung. Bitte \u00fcberpr\u00fcfen Sie die spezifischen Daten in der MT4\/MT5-Software.\n<\/p>\n<p>\n    F\u00fcr weitere Informationen kontaktieren Sie uns bitte unter <a href=\"mailto:info@vtmarkets.com\">info@vtmarkets.com.<\/a>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sehr geehrter Kunde, Bitte beachten Sie, dass die Dividenden der folgenden Produkte entsprechend angepasst werden. Index-Dividenden werden separat \u00fcber eine Kontoabrechnung direkt auf Ihr Handelskonto gebucht. Der Kommentar dazu erfolgt im folgenden Format: \u201eDiv &#038; Produktname &#038; Nettovolumen\u201c. Bitte beachten Sie die folgende Tabelle f\u00fcr weitere Details: Die obigen Daten dienen nur zur Orientierung. Bitte <a href=\"https:\/\/www.vtmarkets.net\/de\/dividend\/v2025081901\/\" class=\"read-more\">Continue Reading<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-17211","post","type-post","status-publish","format-standard","hentry","category-dividend"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.vtmarkets.net\/de\/wp-json\/wp\/v2\/posts\/17211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vtmarkets.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vtmarkets.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vtmarkets.net\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vtmarkets.net\/de\/wp-json\/wp\/v2\/comments?post=17211"}],"version-history":[{"count":0,"href":"https:\/\/www.vtmarkets.net\/de\/wp-json\/wp\/v2\/posts\/17211\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.vtmarkets.net\/de\/wp-json\/wp\/v2\/media?parent=17211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vtmarkets.net\/de\/wp-json\/wp\/v2\/categories?post=17211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vtmarkets.net\/de\/wp-json\/wp\/v2\/tags?post=17211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}